{"id":346,"date":"2025-02-12T06:26:45","date_gmt":"2025-02-12T06:26:45","guid":{"rendered":"https:\/\/www.on-callrx.com\/?page_id=346"},"modified":"2025-09-15T16:39:53","modified_gmt":"2025-09-15T16:39:53","slug":"frequently-asked-questions","status":"publish","type":"page","link":"https:\/\/www.on-callrx.com\/en\/frequently-asked-questions\/","title":{"rendered":"Frequently Asked Questions"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"346\" class=\"elementor elementor-346\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ecee544 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7ecee544\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-983c217\" data-id=\"983c217\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63fbeb54 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"63fbeb54\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">FAQ's<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6eadb996 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"6eadb996\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.on-callrx.com\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Home<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.on-callrx.com\/about\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">About<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-535072f9 e-flex e-con-boxed e-con e-parent\" data-id=\"535072f9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4c5f8c57 e-con-full e-flex e-con e-child\" data-id=\"4c5f8c57\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4fd2a873 elementor-widget elementor-widget-heading\" data-id=\"4fd2a873\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Your Questions, Clearly Answered.<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a03c3cf elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"a03c3cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">Most Popular <span>Questions<\/span><\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1dc7e49b e-con-full e-flex e-con e-child\" data-id=\"1dc7e49b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ba3af89 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"1ba3af89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a97b64e35b29\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-1ba3af89\">\n                        <a href=\"#collapse-bfc498a6a97b64e35b29\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-bfc498a6a97b64e35b29\" aria-expanded=\"true\" aria-controls=\"Collapse-bfc498a6a97b64e35b29\">\n                            \n                            <span class=\"ekit-accordion-title\">Who benefits the most from the On-Call RX Program?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-bfc498a6a97b64e35b29\" class=\" show collapse\" aria-labelledby=\"primaryHeading-0-1ba3af89\" data-parent=\"#accordion-6a97b64e35b29\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>The On-Call RX Program is designed for individuals and families seeking easy, affordable access to healthcare. If you frequently need medical consultations, require daily medications, or want to eliminate the hassle of copays and insurance deductibles, this program is ideal for you. With same-day doctor access and medication delivery, On-Call RX ensures your health needs are met conveniently and efficiently.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-1ba3af89\">\n                        <a href=\"#collapse-9ca623a6a97b64e35b29\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-9ca623a6a97b64e35b29\" aria-expanded=\"false\" aria-controls=\"Collapse-9ca623a6a97b64e35b29\">\n                            \n                            <span class=\"ekit-accordion-title\">What services does On-Call RX offer?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-9ca623a6a97b64e35b29\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-1ba3af89\" data-parent=\"#accordion-6a97b64e35b29\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>On-Call RX provides unlimited virtual doctor visits, access to specialists, mental health support, and a comprehensive prescription medication plan. All consultations are conducted online, eliminating the need for waiting rooms, appointments, or travel. Your medications are either delivered to your door or available for pickup at a local pharmacy.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-1ba3af89\">\n                        <a href=\"#collapse-26956a76a97b64e35b29\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-26956a76a97b64e35b29\" aria-expanded=\"false\" aria-controls=\"Collapse-26956a76a97b64e35b29\">\n                            \n                            <span class=\"ekit-accordion-title\">What payment methods are accepted?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-26956a76a97b64e35b29\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-1ba3af89\" data-parent=\"#accordion-6a97b64e35b29\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>We accept all major debit and credit cards, as well as Google Pay and Apple Pay for secure and convenient transactions.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-1ba3af89\">\n                        <a href=\"#collapse-c34d56d6a97b64e35b29\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-c34d56d6a97b64e35b29\" aria-expanded=\"false\" aria-controls=\"Collapse-c34d56d6a97b64e35b29\">\n                            \n                            <span class=\"ekit-accordion-title\">How do I contact customer support?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-c34d56d6a97b64e35b29\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-1ba3af89\" data-parent=\"#accordion-6a97b64e35b29\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>For assistance, contact our customer support team at <a>support@on-callrx.com<\/a> or call (877) 751-6187. \u00a0We are available to answer any questions and ensure you get the most out of your membership.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f6193fb e-flex e-con-boxed e-con e-parent\" data-id=\"3f6193fb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d50772 e-con-full e-flex e-con e-child\" data-id=\"d50772\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-69832bdc e-con-full e-flex e-con e-child\" data-id=\"69832bdc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-139b292a elementor-widget elementor-widget-heading\" data-id=\"139b292a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Any other questions?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4854a0ac elementor-widget elementor-widget-text-editor\" data-id=\"4854a0ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-pm-slice=\"1 1 []\">Feel free to reach out to us at <a>info@on-callrx.com<\/a> for more information.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75bd8d20 elementor-widget elementor-widget-button\" data-id=\"75bd8d20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.on-callrx.com\/subscription-plans\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Sign Up for On-Call RX Today<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-424c5577 e-flex e-con-boxed e-con e-parent\" data-id=\"424c5577\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3612fba4 e-flex e-con-boxed e-con e-child\" data-id=\"3612fba4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0b95129 elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"0b95129\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">Most Popular <span>Questions<\/span><\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-360f17d3 e-con-full e-flex e-con e-child\" data-id=\"360f17d3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ccac227 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-elementskit-accordion\" data-id=\"4ccac227\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a97b64e4414a\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-4ccac227\">\n                        <a href=\"#collapse-bfc498a6a97b64e4414a\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-bfc498a6a97b64e4414a\" aria-expanded=\"true\" aria-controls=\"Collapse-bfc498a6a97b64e4414a\">\n                            \n                            <span class=\"ekit-accordion-title\">How long does it take to activate my benefits?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-bfc498a6a97b64e4414a\" class=\" show collapse\" aria-labelledby=\"primaryHeading-0-4ccac227\" data-parent=\"#accordion-6a97b64e4414a\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Once you enroll, your benefits are activated the same day. You can consult with a doctor within 2-4 hours and receive medications immediately after your consultation, either at a participating pharmacy or through our delivery service<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-4ccac227\">\n                        <a href=\"#collapse-26eb38e6a97b64e4414a\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-26eb38e6a97b64e4414a\" aria-expanded=\"false\" aria-controls=\"Collapse-26eb38e6a97b64e4414a\">\n                            \n                            <span class=\"ekit-accordion-title\">Can I use On-Call RX with my existing insurance?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-26eb38e6a97b64e4414a\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-4ccac227\" data-parent=\"#accordion-6a97b64e4414a\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Yes! On-Call RX works independently of insurance, providing you with an alternative to expensive copays and high deductibles. Many members find that our program helps them save significantly on their healthcare costs while maintaining the flexibility to use their insurance for other medical needs.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ce49cbf elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-elementskit-accordion\" data-id=\"2ce49cbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a97b64e45bc7\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-2ce49cbf\">\n                        <a href=\"#collapse-bfc498a6a97b64e45bc7\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-bfc498a6a97b64e45bc7\" aria-expanded=\"true\" aria-controls=\"Collapse-bfc498a6a97b64e45bc7\">\n                            \n                            <span class=\"ekit-accordion-title\">What if I want to cancel my membership?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-bfc498a6a97b64e45bc7\" class=\" show collapse\" aria-labelledby=\"primaryHeading-0-2ce49cbf\" data-parent=\"#accordion-6a97b64e45bc7\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>You can cancel your membership at any time. Services will remain active until the end of your billing cycle. To cancel, simply contact us at <a>info@on-callrx.com<\/a>.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-2ce49cbf\">\n                        <a href=\"#collapse-9ca623a6a97b64e45bc7\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-9ca623a6a97b64e45bc7\" aria-expanded=\"false\" aria-controls=\"Collapse-9ca623a6a97b64e45bc7\">\n                            \n                            <span class=\"ekit-accordion-title\">How do I modify or update my membership?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-9ca623a6a97b64e45bc7\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-2ce49cbf\" data-parent=\"#accordion-6a97b64e45bc7\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>To update or modify your membership, email us at <a>info@on-callrx.com<\/a>or visit your account settings on our website.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-2ce49cbf\">\n                        <a href=\"#collapse-acfa4076a97b64e45bc7\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-acfa4076a97b64e45bc7\" aria-expanded=\"false\" aria-controls=\"Collapse-acfa4076a97b64e45bc7\">\n                            \n                            <span class=\"ekit-accordion-title\">How do I access telemedicine services?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-acfa4076a97b64e45bc7\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-2ce49cbf\" data-parent=\"#accordion-6a97b64e45bc7\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Upon enrollment, you will receive login credentials to our online patient portal. From there, you can schedule virtual doctor visits, consult specialists, and manage your prescriptions all from the comfort of your home.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c2da342 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c2da342\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76646c3\" data-id=\"76646c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93d06ac elementor-widget elementor-widget-pp-logo-carousel\" data-id=\"93d06ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;pause_on_hover&quot;:&quot;yes&quot;}\" data-widget_type=\"pp-logo-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"swiper-container-wrap\">\n\t\t\t<div class=\"pp-logo-carousel pp-swiper-slider swiper\" data-slider-settings=\"{&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:400,&quot;slides_per_view&quot;:3,&quot;space_between&quot;:10,&quot;auto_height&quot;:false,&quot;loop&quot;:&quot;yes&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:3000,&quot;pause_on_interaction&quot;:&quot;&quot;,&quot;show_arrows&quot;:true,&quot;slides_per_view_mobile&quot;:1,&quot;space_between_mobile&quot;:10,&quot;slides_per_view_tablet&quot;:2,&quot;space_between_tablet&quot;:10}\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<div class=\"pp-lc-logo-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-lc-logo\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/cdn.on-callrx.com\/wp-content\/uploads\/2025\/02\/cvs.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<div class=\"pp-lc-logo-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-lc-logo\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/cdn.on-callrx.com\/wp-content\/uploads\/2025\/02\/Walgreen.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<div class=\"pp-lc-logo-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-lc-logo\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/cdn.on-callrx.com\/wp-content\/uploads\/2025\/02\/walmart.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<div class=\"pp-lc-logo-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-lc-logo\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/cdn.on-callrx.com\/wp-content\/uploads\/2025\/02\/kroger.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<div class=\"pp-lc-logo-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-lc-logo\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/cdn.on-callrx.com\/wp-content\/uploads\/2025\/02\/safeway.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<div class=\"pp-lc-logo-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-lc-logo\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/cdn.on-callrx.com\/wp-content\/uploads\/2025\/02\/wegmans.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"pp-slider-arrow elementor-swiper-button-prev swiper-button-prev-93d06ac\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-left\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"pp-slider-arrow elementor-swiper-button-next swiper-button-next-93d06ac\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t<\/div>\n\t\t\t<div class=\"pp-screen-only elementor-screen-only\" aria-live=\"polite\" id=\"pp-logo-carousel-status\">Showing Slide 1 of 6<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec96cec elementor-widget elementor-widget-heading\" data-id=\"ec96cec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Accepted at 70,000 pharmacy's nationwide<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>FAQ&#8217;s Home About Your Questions, Clearly Answered. Most Popular Questions Who benefits the most from the On-Call RX Program? The On-Call RX Program is designed for individuals and families seeking easy, affordable access to healthcare. If you frequently need medical consultations, require daily medications, or want to eliminate the hassle of copays and insurance deductibles, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-346","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.on-callrx.com\/en\/wp-json\/wp\/v2\/pages\/346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.on-callrx.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.on-callrx.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.on-callrx.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.on-callrx.com\/en\/wp-json\/wp\/v2\/comments?post=346"}],"version-history":[{"count":0,"href":"https:\/\/www.on-callrx.com\/en\/wp-json\/wp\/v2\/pages\/346\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.on-callrx.com\/en\/wp-json\/wp\/v2\/media?parent=346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}